{"id":2480,"date":"2022-08-12T09:04:05","date_gmt":"2022-08-12T07:04:05","guid":{"rendered":"https:\/\/cftc-sicsti.fr\/cognizant2\/?p=2480"},"modified":"2022-08-12T09:04:05","modified_gmt":"2022-08-12T07:04:05","slug":"cfp-ne-pas-oublier","status":"publish","type":"post","link":"https:\/\/cftc-sicsti.fr\/cognizant2\/cfp-ne-pas-oublier\/","title":{"rendered":"CFP : ne pas oublier &#8230;"},"content":{"rendered":"<p>La CFP est une institution chez Capgemini depuis des dizaines d&rsquo;ann\u00e9es mais de nombreux coll\u00e8gues ne l&rsquo;utilisent pas ou ne la connaissent m\u00eame pas&#8230;<\/p>\n<p>Et quand ils l&rsquo;utilisent, ils ont tendance \u00e0 ne pas tenir compte des nombreux conseils donn\u00e9es par cette instance paritaire qui se r\u00e9unit syst\u00e9matiquement tous les mois pour d\u00e9terminer une r\u00e9ponse claire aux demandes de formation.<\/p>\n<h2>Donc, ci-dessous, quelques rappels \u00e0 ne pas oublier !<\/h2>\n<ul>\n<li>ne pas oublier que le site de la CFP est disponible \u00e0 partir du r\u00e9seau Capgemini ici : <a href=\"https:\/\/cfp.fr.capgemini.com\/\">https:\/\/cfp.fr.capgemini.com\/<\/a><\/li>\n<li>ne pas oublier de consulter ce <a href=\"https:\/\/cfp.fr.capgemini.com\/Telecharger.aspx?Fichier=Regles\">document<\/a> pour avoir la liste des centres de formation pour un permis voiture ou bateau<\/li>\n<li>\n<h3><strong>ne pas oublier de lire les <a href=\"https:\/\/cfp.fr.capgemini.com\/Telecharger.aspx?Fichier=Reglement\">r\u00e8gles de fonctionnement<\/a> comportant entre autres le mail du centre de gestion de la CFP ainsi que toutes les explications sur le fonctionnement de la CFP !<\/strong><\/h3>\n<\/li>\n<li>ne pas oublier de passer un test d&rsquo;anglais pour les stages en immersion \u00e0 l&rsquo;\u00e9tranger (qui ont toujours beaucoup de succ\u00e8s ) !<\/li>\n<li>ne pas oublier que nous disposons tous d&rsquo;un <a href=\"http:\/\/www.moncompteformation.gouv.fr\/\">CPF<\/a> qui, pour certains, attendra son maximum de 5000\u20ac d&rsquo;ici moins de 2 ans !<\/li>\n<li>ne pas oublier de regarder la liste des sessions qui disposent encore de places et les relances qui sont g\u00e9n\u00e9ralement affich\u00e9es pr\u00e8s du gestionnaires local des activit\u00e9s sociales et culturelles (\u00ab\u00a0les relances\u00a0\u00bb)<\/li>\n<li>Ne pas oublier de respecter la <a href=\"https:\/\/talent.capgemini.com\/fr\/pages\/infos_sociales\/informations_communes\/rubrique_du_salari\/notes_de_services\/\">note sur les modalit\u00e9s de remboursement des frais professionnels<\/a>\u00a0 et aussi d&rsquo;informer son manager si ces modalit\u00e9s viennent \u00e0 \u00eatre remises en cause lors du d\u00e9placement vers votre formation CFP<\/li>\n<li>Ne pas oublier de consulter la fiche descriptive de son stage<\/li>\n<\/ul>\n<p><strong>Ne pas oublier enfin que D.Moreau et moi-m\u00eame, G.Dacheux, sommes \u00e0 votre disposition pour \u00e9changer sur ces sujets !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La CFP est une institution chez Capgemini depuis des dizaines d&rsquo;ann\u00e9es mais de nombreux coll\u00e8gues ne l&rsquo;utilisent pas ou ne la connaissent m\u00eame pas&#8230; Et quand ils l&rsquo;utilisent, ils ont tendance \u00e0 ne pas tenir compte des nombreux conseils donn\u00e9es par cette instance paritaire qui se r\u00e9unit syst\u00e9matiquement tous les mois pour d\u00e9terminer une r\u00e9ponse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formation"],"_links":{"self":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/posts\/2480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/comments?post=2480"}],"version-history":[{"count":0,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/posts\/2480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/media\/2481"}],"wp:attachment":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/media?parent=2480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/categories?post=2480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/tags?post=2480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}