{"id":1718,"date":"2021-05-23T12:07:10","date_gmt":"2021-05-23T10:07:10","guid":{"rendered":"https:\/\/cftc-sicsti.fr\/cognizant2\/numerrobotethique\/"},"modified":"2021-05-23T12:07:10","modified_gmt":"2021-05-23T10:07:10","slug":"numerrobotethique","status":"publish","type":"post","link":"https:\/\/cftc-sicsti.fr\/cognizant2\/numerrobotethique\/","title":{"rendered":"(num\u00e9r|robot|\u00e9th)ique ?"},"content":{"rendered":"\n\n<h2>Num\u00e9rique, robotique : quelle \u00e9thique pour le monde du travail (de demain) ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Notre conf\u00e9d\u00e9ration a r\u00e9alis\u00e9 une \u00e9tude intitul\u00e9e <em>\u00ab\u00a0num\u00e9rique, robotique : quelle \u00e9thique pour le monde du travail (de demain) ?\u00a0\u00bb<\/em> dans le cadre de l?EUR(TM)agence d?EUR(TM)objectifs de l?EUR(TM)Institut de recherches \u00e9conomiques et sociales (IRES).<\/p>\n\n\n\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p>\u00ab?EUR,Cette collection, con\u00e7ue pour les acteurs de terrain, syndicalistes ou non, propose des analyses et r\u00e9flexions sur les grands d\u00e9fis \u00e9conomiques et sociaux d?EUR(TM)aujourd?EUR(TM)hui. S?EUR(TM)inspirant des principes sociaux chr\u00e9tiens, cette s\u00e9rie d?EUR(TM)ouvrages esquisse les contours d?EUR(TM)une soci\u00e9t\u00e9 o\u00f9 l?EUR(TM)homme aurait pr\u00e9\u00e9minence sur la logique \u00e9conomique.?EUR,\u00bb<\/p>\n\n<\/blockquote>\n\n\n\n\n\n\n\n<h2>Pav\u00e9 de 210 pages !<\/h2>\n\n<p class=\"wp-block-paragraph\">Ce pav\u00e9 CFTC de 210 pages m\u00e9rite d&rsquo;\u00eatre lu (j&rsquo;ai pas fini&#8230;) pour son \u00e9clairage complet des probl\u00e9matiques apport\u00e9es par la science dans le monde du travail notamment avec l&rsquo;immixtion du num\u00e9rique et de ses corollaires : IA, RGPD, Big Data&#8230;<\/p>\n\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Cet ouvrage, qu&rsquo;on aurait pu sortir plus t\u00f4t (?), n&rsquo;est disponible que pour les adh\u00e9rents CFTC, une fois connect\u00e9s &#8230; sur leur espace adh\u00e9rent !<\/p>\n\n\n\n\n\n\n\n<h2>Introduction &#8230; de l&rsquo;introduction &#8230; ci-apr\u00e8s&#8230;<\/h2>\n\n<blockquote>\n\n<p class=\"wp-block-paragraph\">La science et son usage ont de tout temps suscit\u00e9 l?EUR(TM)enthousiasme et la d\u00e9fiance. Nombreux sont les philosophes qui se sont empar\u00e9s de cette probl\u00e9matique de r\u00e9flexion. Pour Fran\u00e7ois Rabelais, humaniste de la Renaissance, \u00ab Science sans conscience n?EUR(TM)est que ruine de l?EUR(TM)\u00e2me \u00bb. Par cette c\u00e9l\u00e8bre sentence, il alerte sur les possibles dangers d?EUR(TM)une science sur laquelle l?EUR(TM)homme n?EUR(TM)aurait pas de regard critique, une pens\u00e9e responsable<\/p>\n\n<\/blockquote>\n\n\n\n\n\n\n\n<figure class=\"wp-block-pullquote\"><\/figure>\n\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/cftc.fr\/espace-adherent\/wp-content\/uploads\/sites\/176\/sites\/11\/sites\/2\/2021\/05\/livre-numerique-robotique-web.pdf\"><img decoding=\"async\" class=\"aligncenter wp-image-3050 size-medium\" src=\"http:\/\/cftc-sicsti.fr\/cognizant2\/testimport\/wp-content\/uploads\/sites\/176\/sites\/11\/2021\/05\/numerique.jpg\" alt=\"\" width=\"600\" \/><\/a><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Num\u00e9rique, robotique : quelle \u00e9thique pour le monde du travail (de demain) ? Notre conf\u00e9d\u00e9ration a r\u00e9alis\u00e9 une \u00e9tude intitul\u00e9e \u00ab\u00a0num\u00e9rique, robotique : quelle \u00e9thique pour le monde du travail (de demain) ?\u00a0\u00bb dans le cadre de l?EUR(TM)agence d?EUR(TM)objectifs de l?EUR(TM)Institut de recherches \u00e9conomiques et sociales (IRES). \u00ab?EUR,Cette collection, con\u00e7ue pour les acteurs de terrain, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-1718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ia"],"_links":{"self":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/posts\/1718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/comments?post=1718"}],"version-history":[{"count":0,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/posts\/1718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/media\/1719"}],"wp:attachment":[{"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/media?parent=1718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/categories?post=1718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cftc-sicsti.fr\/cognizant2\/wp-json\/wp\/v2\/tags?post=1718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}